{"id":257,"date":"2017-09-26T11:04:44","date_gmt":"2017-09-26T11:04:44","guid":{"rendered":"http:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1.jpg"},"modified":"2017-12-07T08:23:58","modified_gmt":"2017-12-07T08:23:58","slug":"diapositive1","status":"inherit","type":"attachment","link":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/diapositive1\/","title":{"rendered":"Diapositive1"},"author":124,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-257","attachment","type-attachment","status-inherit","czr-hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a class=\"grouped_elements\" rel=\"tc-fancybox-group\" href=\"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-e1506961466632.jpg\" title=\"Diapositive1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-300x225.jpg 300w, https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-768x576.jpg 768w, https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-e1506961466632.jpg 860w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":860,"height":645,"file":"2017\/09\/Diapositive1-e1506961466632.jpg","sizes":{"thumbnail":{"file":"Diapositive1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-150x150.jpg"},"medium":{"file":"Diapositive1-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-300x225.jpg"},"medium_large":{"file":"Diapositive1-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-768x576.jpg"},"tc-grid-full":{"file":"Diapositive1-960x350.jpg","width":960,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-960x350.jpg"},"tc-grid":{"file":"Diapositive1-570x350.jpg","width":570,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-570x350.jpg"},"tc-thumb":{"file":"Diapositive1-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-270x250.jpg"},"slider-full":{"file":"Diapositive1-960x400.jpg","width":960,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-960x400.jpg"},"slider":{"file":"Diapositive1-960x400.jpg","width":960,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-960x400.jpg"},"fpc-size":{"file":"Diapositive1-270x250.jpg","width":270,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-270x250.jpg"},"full":{"file":"Diapositive1-e1506961466632.jpg","width":860,"height":645,"mime_type":"image\/jpeg","source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-e1506961466632.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-content\/uploads\/sites\/20\/2017\/09\/Diapositive1-e1506961466632.jpg","_links":{"self":[{"href":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-json\/wp\/v2\/media\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-json\/wp\/v2\/users\/124"}],"replies":[{"embeddable":true,"href":"https:\/\/ee.mlfmonde.org\/muanda-perenco\/wp-json\/wp\/v2\/comments?post=257"}]}}